{"id":132,"date":"2009-02-05T12:20:38","date_gmt":"2009-02-05T10:20:38","guid":{"rendered":"http:\/\/www.rafcano.es\/blog\/?p=132"},"modified":"2009-02-05T12:20:38","modified_gmt":"2009-02-05T10:20:38","slug":"cuando-una-asignatura-te-supera","status":"publish","type":"post","link":"http:\/\/www.rafcano.es\/blog\/2009\/02\/cuando-una-asignatura-te-supera\/","title":{"rendered":"Cuando una asignatura te supera"},"content":{"rendered":"<p>Me encuentro a unas horas antes del examen de Control Digital, una asignatura optativa de quinto de I.T.S. Inform\u00e1tica que he cursado este a\u00f1o. Creo que es <strong>el momento m\u00e1s <\/strong><strong>deprimente de toda mi vida<\/strong>, incluso m\u00e1s que cuando sal\u00ed de mi primer examen de C\u00e1lculo a la media hora de entrar, con el examen en la mano y una pregunta a medio hacer.<\/p>\n<p>Cuando ped\u00ed consejo sobre la asignatura a gente que ya hab\u00eda cursado el segundo ciclo, ninguno supo decirme si la asignatura era <em>recomendable<\/em> o <em>no recomendable<\/em>. Ahora entiendo el porqu\u00e9: a nadie se le hab\u00eda ocurrido cogerla. Y lo entiendo, sobre todo si vienes de I.T. Inform\u00e1tica de Gesti\u00f3n, donde <strong>has visto mucha econom\u00eda y gesti\u00f3n de empresas y poca electr\u00f3nica digital<\/strong>.<\/p>\n<p>Durante el curso me sorprend\u00eda ver tanta ecuaci\u00f3n, tanta integral, tanta transformada (aqu\u00ed detallar que en las matem\u00e1ticas I, II y III cursadas anteriormente, nunca vimos transformadas, por lo que era un concepto nuevo que sigo sin comprender), tantos conceptos nuevos y raros, etc. Yo, como <strong>hombre que nunca se rinde<\/strong>, segu\u00ed con ella: fui a todas las clases que pod\u00eda, realic\u00e9 todas las pr\u00e1cticas de laboratorio, present\u00e9 todas las memorias de las pr\u00e1cticas&#8230; vamos, que <em>currada <\/em>estaba la asignatura. Incluso cre\u00eda que la llegaba a entender, todos esos conceptos extra\u00f1os.<\/p>\n<p>Pero la hora de la verdad ha llegado. Despu\u00e9s de curr\u00e1rmela, estudiarla y repasarla durante todo el curso, ahora a unas horas antes del examen, sigo con el repaso final. Y sigo con \u00e9l porque de los tres ex\u00e1menes ejemplo que nos dej\u00f3 el profesor, a ninguno llego a cinco puntos m\u00ednimos exigidos con mis respuestas. Simplemente, no s\u00e9 qu\u00e9 me est\u00e1 preguntando, no s\u00e9 qu\u00e9 responder a las preguntas, <strong>no s\u00e9 nada<\/strong>.<\/p>\n<p>Ahora creo que esta asignatura no es lo que yo cre\u00eda que iba a a ser, no es lo que esperaba, no cumpli\u00f3 con mis expectativas&#8230; vamos, que seg\u00fan mi humilde opini\u00f3n <strong>es dif\u00edcil, fea e incomprensible<\/strong>. Al menos para mis conocimientos previos en la materia.<\/p>\n<p>Me presentar\u00e9 por eso de \u00ab<em>a ver si aparece la Virgen<\/em>\u00bb y porque creo que <strong>rendirse es de cobardes, y los cobardes no tienen sitio en este planeta<\/strong> (ese consejo me lo dio mi madre en un momento dif\u00edcil y siempre que le aplico, me va bien). Pero, sinceramente, no creo que apruebe, que llegue a los puntos m\u00ednimos exigidos.<\/p>\n<p>La buena noticia: es optativa, por lo que entra dentro del grupo de las <em>abandonables<\/em>, lo cual quiere decir que al a\u00f1o que viene podr\u00eda matricularme de otra asignatura optativa distinta sin problema alguno. Y esta vez s\u00ed que <strong>s\u00f3lo coger\u00e9 aquellas asignaturas que me recomienden<\/strong>, aquellas que previamente otras personas marcaron como <em>recomendables<\/em> en su lista de preferencias, que aquellas que previamente me recomendaron, fueron buena elecci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me encuentro a unas horas antes del examen de Control Digital, una asignatura optativa de quinto de I.T.S. Inform\u00e1tica que he cursado este a\u00f1o. Creo que es el momento m\u00e1s deprimente de toda mi vida, incluso m\u00e1s que cuando sal\u00ed de mi primer examen de C\u00e1lculo a la media hora de entrar, con el examen &hellip; <a href=\"http:\/\/www.rafcano.es\/blog\/2009\/02\/cuando-una-asignatura-te-supera\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Cuando una asignatura te supera<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[212,8],"tags":[215,214,30,198,213,307,216,81],"class_list":["post-132","post","type-post","status-publish","format-standard","hentry","category-estudios","category-informatica","tag-calculo","tag-control-digital","tag-examenes","tag-it-informatica-de-gestion","tag-its-informatica","tag-informatica","tag-recomendacion","tag-universidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/poH0Z-28","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":0,"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rafcano.es\/blog\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}